{"id":1552,"date":"2023-09-06T10:49:08","date_gmt":"2023-09-06T10:49:08","guid":{"rendered":"https:\/\/abicont.com\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/"},"modified":"2023-09-06T12:10:28","modified_gmt":"2023-09-06T12:10:28","slug":"recollida-gestio-i-venda-denvasos-de-1-000-litres","status":"publish","type":"page","link":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/","title":{"rendered":"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":101017,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1552","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres - Abicont<\/title>\n<meta name=\"description\" content=\"Si vols m\u00e9s informaci\u00f3 sobre els nostres serveis o, sol\u00b7licitar un pressupost sense comprom\u00eds, no dubtis a contactar amb nosaltres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres - Abicont\" \/>\n<meta property=\"og:description\" content=\"Si vols m\u00e9s informaci\u00f3 sobre els nostres serveis o, sol\u00b7licitar un pressupost sense comprom\u00eds, no dubtis a contactar amb nosaltres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/\" \/>\n<meta property=\"og:site_name\" content=\"Abicont\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-06T12:10:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abicont.com\/wp-content\/uploads\/2023\/08\/abicont_logo-green.png\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abicont.com\\\/ca\\\/recollida-gestio-i-venda-denvasos-de-1-000-litres\\\/\",\"url\":\"https:\\\/\\\/abicont.com\\\/ca\\\/recollida-gestio-i-venda-denvasos-de-1-000-litres\\\/\",\"name\":\"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres - Abicont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abicont.com\\\/#website\"},\"datePublished\":\"2023-09-06T10:49:08+00:00\",\"dateModified\":\"2023-09-06T12:10:28+00:00\",\"description\":\"Si vols m\u00e9s informaci\u00f3 sobre els nostres serveis o, sol\u00b7licitar un pressupost sense comprom\u00eds, no dubtis a contactar amb nosaltres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abicont.com\\\/ca\\\/recollida-gestio-i-venda-denvasos-de-1-000-litres\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abicont.com\\\/ca\\\/recollida-gestio-i-venda-denvasos-de-1-000-litres\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abicont.com\\\/ca\\\/recollida-gestio-i-venda-denvasos-de-1-000-litres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/abicont.com\\\/ca\\\/inici\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abicont.com\\\/#website\",\"url\":\"https:\\\/\\\/abicont.com\\\/\",\"name\":\"Abicont\",\"description\":\"Log\u00edstica de mercanc\u00edas, valorizaci\u00f3n de residuos industriales i retirada de residuos l\u00edquidos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abicont.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres - Abicont","description":"Si vols m\u00e9s informaci\u00f3 sobre els nostres serveis o, sol\u00b7licitar un pressupost sense comprom\u00eds, no dubtis a contactar amb nosaltres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/","og_locale":"ca_ES","og_type":"article","og_title":"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres - Abicont","og_description":"Si vols m\u00e9s informaci\u00f3 sobre els nostres serveis o, sol\u00b7licitar un pressupost sense comprom\u00eds, no dubtis a contactar amb nosaltres.","og_url":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/","og_site_name":"Abicont","article_modified_time":"2023-09-06T12:10:28+00:00","og_image":[{"width":663,"height":130,"url":"https:\/\/abicont.com\/wp-content\/uploads\/2023\/08\/abicont_logo-green.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/","url":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/","name":"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres - Abicont","isPartOf":{"@id":"https:\/\/abicont.com\/#website"},"datePublished":"2023-09-06T10:49:08+00:00","dateModified":"2023-09-06T12:10:28+00:00","description":"Si vols m\u00e9s informaci\u00f3 sobre els nostres serveis o, sol\u00b7licitar un pressupost sense comprom\u00eds, no dubtis a contactar amb nosaltres.","breadcrumb":{"@id":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abicont.com\/ca\/recollida-gestio-i-venda-denvasos-de-1-000-litres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/abicont.com\/ca\/inici\/"},{"@type":"ListItem","position":2,"name":"Recollida, gesti\u00f3 i venda d\u00b4envasos de 1.000 litres"}]},{"@type":"WebSite","@id":"https:\/\/abicont.com\/#website","url":"https:\/\/abicont.com\/","name":"Abicont","description":"Log\u00edstica de mercanc\u00edas, valorizaci\u00f3n de residuos industriales i retirada de residuos l\u00edquidos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abicont.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/pages\/1552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/users\/101017"}],"replies":[{"embeddable":true,"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/comments?post=1552"}],"version-history":[{"count":1,"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/pages\/1552\/revisions"}],"predecessor-version":[{"id":1567,"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/pages\/1552\/revisions\/1567"}],"wp:attachment":[{"href":"https:\/\/abicont.com\/ca\/wp-json\/wp\/v2\/media?parent=1552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}